{"id":274,"count":57,"description":"","link":"https:\/\/dragonalliance.com.au\/nz\/category\/polarised\/","name":"Polarised","slug":"polarised","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":36,"_links":{"self":[{"href":"https:\/\/dragonalliance.com.au\/nz\/wp-json\/wp\/v2\/product_cat\/274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dragonalliance.com.au\/nz\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/dragonalliance.com.au\/nz\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/dragonalliance.com.au\/nz\/wp-json\/wp\/v2\/product?product_cat=274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}